{"id":3800,"count":1,"description":"","link":"https:\/\/ardesia.ee\/ru\/engine-type\/b5244s2\/","name":"B5244S2","slug":"b5244s2","taxonomy":"engine-type","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/engine-type\/3800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/engine-type"}],"about":[{"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/taxonomies\/engine-type"}],"wp:post_type":[{"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/estate?engine-type=3800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}