{"id":10015,"date":"2021-12-02T13:20:38","date_gmt":"2021-12-02T11:20:38","guid":{"rendered":"https:\/\/ardesia.ee\/?post_type=estate&#038;p=10015"},"modified":"2021-12-02T13:20:38","modified_gmt":"2021-12-02T11:20:38","slug":"renault-laguna-2001-2007-wagon-5","status":"publish","type":"estate","link":"https:\/\/ardesia.ee\/ru\/catalogue\/renault-laguna-2001-2007-wagon-5\/","title":{"rendered":"Renault Laguna 2001-2007 Wagon"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","property-type":[],"offer-type":[],"make":[237],"model":[595],"sub-model-modification":[1154],"transmission":[186],"engine":[318],"body-type":[194],"fuel":[],"drivetrain":[200],"door-count":[205],"reg--date":[2105],"gearbox-type":[],"engine-type":[],"vin":[3295],"class_list":["post-10015","estate","type-estate","status-publish","hentry","make-renault","model-laguna","sub-model-modification-laguna-2001-2007-wagon","transmission-manual","engine-2-0i","body-type-wagon","drivetrain-fwd","door-count-205","reg--date-08-2004","vin-vf1kg0s0632071893"],"acf":[],"_links":{"self":[{"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/estate\/10015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/estate"}],"about":[{"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/types\/estate"}],"author":[{"embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/media?parent=10015"}],"wp:term":[{"taxonomy":"property-type","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/property-type?post=10015"},{"taxonomy":"offer-type","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/offer-type?post=10015"},{"taxonomy":"make","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/make?post=10015"},{"taxonomy":"model","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/model?post=10015"},{"taxonomy":"sub-model-modification","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/sub-model-modification?post=10015"},{"taxonomy":"transmission","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/transmission?post=10015"},{"taxonomy":"engine","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/engine?post=10015"},{"taxonomy":"body-type","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/body-type?post=10015"},{"taxonomy":"fuel","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/fuel?post=10015"},{"taxonomy":"drivetrain","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/drivetrain?post=10015"},{"taxonomy":"door-count","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/door-count?post=10015"},{"taxonomy":"reg--date","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/reg--date?post=10015"},{"taxonomy":"gearbox-type","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/gearbox-type?post=10015"},{"taxonomy":"engine-type","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/engine-type?post=10015"},{"taxonomy":"vin","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/vin?post=10015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}