{"id":12598,"date":"2021-12-02T20:26:16","date_gmt":"2021-12-02T18:26:16","guid":{"rendered":"https:\/\/ardesia.ee\/?post_type=estate&#038;p=12598"},"modified":"2021-12-02T20:26:51","modified_gmt":"2021-12-02T18:26:51","slug":"volkswagen-polo-1996-1999-sedan-3","status":"publish","type":"estate","link":"https:\/\/ardesia.ee\/ru\/catalogue\/volkswagen-polo-1996-1999-sedan-3\/","title":{"rendered":"Volkswagen Polo 1996-1999 Sedan"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","property-type":[],"offer-type":[],"make":[247],"model":[690],"sub-model-modification":[1348],"transmission":[186],"engine":[1404],"body-type":[193],"fuel":[],"drivetrain":[],"door-count":[204],"reg--date":[1363],"gearbox-type":[],"engine-type":[],"vin":[4098],"class_list":["post-12598","estate","type-estate","status-publish","hentry","make-volkswagen","model-polo","sub-model-modification-polo-1996-1999-sedan","transmission-manual","engine-1-9d","body-type-sedan","door-count-204","reg--date-1363","vin-wvwzzz6kzwr541176"],"acf":[],"_links":{"self":[{"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/estate\/12598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/estate"}],"about":[{"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/types\/estate"}],"author":[{"embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/media?parent=12598"}],"wp:term":[{"taxonomy":"property-type","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/property-type?post=12598"},{"taxonomy":"offer-type","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/offer-type?post=12598"},{"taxonomy":"make","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/make?post=12598"},{"taxonomy":"model","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/model?post=12598"},{"taxonomy":"sub-model-modification","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/sub-model-modification?post=12598"},{"taxonomy":"transmission","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/transmission?post=12598"},{"taxonomy":"engine","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/engine?post=12598"},{"taxonomy":"body-type","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/body-type?post=12598"},{"taxonomy":"fuel","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/fuel?post=12598"},{"taxonomy":"drivetrain","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/drivetrain?post=12598"},{"taxonomy":"door-count","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/door-count?post=12598"},{"taxonomy":"reg--date","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/reg--date?post=12598"},{"taxonomy":"gearbox-type","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/gearbox-type?post=12598"},{"taxonomy":"engine-type","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/engine-type?post=12598"},{"taxonomy":"vin","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/vin?post=12598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}