{"id":7732,"date":"2021-12-01T18:47:23","date_gmt":"2021-12-01T16:47:23","guid":{"rendered":"https:\/\/ardesia.ee\/?post_type=estate&#038;p=7732"},"modified":"2021-12-01T18:47:23","modified_gmt":"2021-12-01T16:47:23","slug":"mitsubishi-pajero-2000-2006-suv","status":"publish","type":"estate","link":"https:\/\/ardesia.ee\/ru\/catalogue\/mitsubishi-pajero-2000-2006-suv\/","title":{"rendered":"Mitsubishi Pajero 2000-2006 SUV"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","property-type":[],"offer-type":[],"make":[232],"model":[534],"sub-model-modification":[1031],"transmission":[186],"engine":[2533],"body-type":[188],"fuel":[],"drivetrain":[199],"door-count":[205],"reg--date":[2630],"gearbox-type":[],"engine-type":[],"vin":[2631],"class_list":["post-7732","estate","type-estate","status-publish","hentry","make-mitsubishi","model-pajero","sub-model-modification-pajero-2000-2006-suv","transmission-manual","engine-3-2d","body-type-suv","drivetrain-awd","door-count-205","reg--date-12-07-2001","vin-jmblyv78w1j006452"],"acf":[],"_links":{"self":[{"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/estate\/7732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/estate"}],"about":[{"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/types\/estate"}],"author":[{"embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/media?parent=7732"}],"wp:term":[{"taxonomy":"property-type","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/property-type?post=7732"},{"taxonomy":"offer-type","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/offer-type?post=7732"},{"taxonomy":"make","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/make?post=7732"},{"taxonomy":"model","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/model?post=7732"},{"taxonomy":"sub-model-modification","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/sub-model-modification?post=7732"},{"taxonomy":"transmission","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/transmission?post=7732"},{"taxonomy":"engine","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/engine?post=7732"},{"taxonomy":"body-type","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/body-type?post=7732"},{"taxonomy":"fuel","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/fuel?post=7732"},{"taxonomy":"drivetrain","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/drivetrain?post=7732"},{"taxonomy":"door-count","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/door-count?post=7732"},{"taxonomy":"reg--date","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/reg--date?post=7732"},{"taxonomy":"gearbox-type","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/gearbox-type?post=7732"},{"taxonomy":"engine-type","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/engine-type?post=7732"},{"taxonomy":"vin","embeddable":true,"href":"https:\/\/ardesia.ee\/ru\/wp-json\/wp\/v2\/vin?post=7732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}